{"id":26446,"date":"2020-02-18T12:04:52","date_gmt":"2020-02-27T20:07:11","guid":{"rendered":"https:\/\/www.groupeplastika.com\/?post_type=product&#038;p=26446"},"modified":"2020-03-11T15:55:09","modified_gmt":"2020-03-11T19:55:09","slug":"frontier-vented-soffit-board-akf-vent8","status":"publish","type":"product","link":"https:\/\/www.groupeplastika.com\/en\/produit\/frontier-vented-soffit-board-akf-vent8\/","title":{"rendered":"Frontier Vented Soffit Board"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":26103,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[9659],"product_tag":[10044,10051],"class_list":{"0":"post-26446","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-soffits","7":"product_tag-new-products-2020","8":"product_tag-new-products-2020-soffits","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Frontier Vented Soffit Board - Groupe Plastika<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.groupeplastika.com\/en\/produit\/frontier-vented-soffit-board-akf-vent8\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frontier Vented Soffit Board - Groupe Plastika\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.groupeplastika.com\/en\/produit\/frontier-vented-soffit-board-akf-vent8\/\" \/>\n<meta property=\"og:site_name\" content=\"Groupe Plastika\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-11T19:55:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.groupeplastika.com\/wp-content\/uploads\/2020\/02\/akf-vent8-8-12-50.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1155\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/frontier-vented-soffit-board-akf-vent8\\\/\",\"url\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/frontier-vented-soffit-board-akf-vent8\\\/\",\"name\":\"Frontier Vented Soffit Board - Groupe Plastika\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/frontier-vented-soffit-board-akf-vent8\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/frontier-vented-soffit-board-akf-vent8\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.groupeplastika.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/akf-vent8-8-12-50.png\",\"datePublished\":\"2020-02-27T20:07:11+00:00\",\"dateModified\":\"2020-03-11T19:55:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/frontier-vented-soffit-board-akf-vent8\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/frontier-vented-soffit-board-akf-vent8\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/frontier-vented-soffit-board-akf-vent8\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.groupeplastika.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/akf-vent8-8-12-50.png\",\"contentUrl\":\"https:\\\/\\\/www.groupeplastika.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/akf-vent8-8-12-50.png\",\"width\":1920,\"height\":1155},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/frontier-vented-soffit-board-akf-vent8\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Frontier Vented Soffit Board\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/#website\",\"url\":\"https:\\\/\\\/www.groupeplastika.com\\\/\",\"name\":\"Groupe Plastika\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.groupeplastika.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frontier Vented Soffit Board - Groupe Plastika","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.groupeplastika.com\/en\/produit\/frontier-vented-soffit-board-akf-vent8\/","og_locale":"en_US","og_type":"article","og_title":"Frontier Vented Soffit Board - Groupe Plastika","og_url":"https:\/\/www.groupeplastika.com\/en\/produit\/frontier-vented-soffit-board-akf-vent8\/","og_site_name":"Groupe Plastika","article_modified_time":"2020-03-11T19:55:09+00:00","og_image":[{"width":1920,"height":1155,"url":"https:\/\/www.groupeplastika.com\/wp-content\/uploads\/2020\/02\/akf-vent8-8-12-50.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.groupeplastika.com\/en\/produit\/frontier-vented-soffit-board-akf-vent8\/","url":"https:\/\/www.groupeplastika.com\/en\/produit\/frontier-vented-soffit-board-akf-vent8\/","name":"Frontier Vented Soffit Board - Groupe Plastika","isPartOf":{"@id":"https:\/\/www.groupeplastika.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.groupeplastika.com\/en\/produit\/frontier-vented-soffit-board-akf-vent8\/#primaryimage"},"image":{"@id":"https:\/\/www.groupeplastika.com\/en\/produit\/frontier-vented-soffit-board-akf-vent8\/#primaryimage"},"thumbnailUrl":"https:\/\/www.groupeplastika.com\/wp-content\/uploads\/2020\/02\/akf-vent8-8-12-50.png","datePublished":"2020-02-27T20:07:11+00:00","dateModified":"2020-03-11T19:55:09+00:00","breadcrumb":{"@id":"https:\/\/www.groupeplastika.com\/en\/produit\/frontier-vented-soffit-board-akf-vent8\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.groupeplastika.com\/en\/produit\/frontier-vented-soffit-board-akf-vent8\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.groupeplastika.com\/en\/produit\/frontier-vented-soffit-board-akf-vent8\/#primaryimage","url":"https:\/\/www.groupeplastika.com\/wp-content\/uploads\/2020\/02\/akf-vent8-8-12-50.png","contentUrl":"https:\/\/www.groupeplastika.com\/wp-content\/uploads\/2020\/02\/akf-vent8-8-12-50.png","width":1920,"height":1155},{"@type":"BreadcrumbList","@id":"https:\/\/www.groupeplastika.com\/en\/produit\/frontier-vented-soffit-board-akf-vent8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.groupeplastika.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.groupeplastika.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Frontier Vented Soffit Board"}]},{"@type":"WebSite","@id":"https:\/\/www.groupeplastika.com\/#website","url":"https:\/\/www.groupeplastika.com\/","name":"Groupe Plastika","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.groupeplastika.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/product\/26446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/comments?post=26446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/media\/26103"}],"wp:attachment":[{"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/media?parent=26446"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/product_brand?post=26446"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/product_cat?post=26446"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/product_tag?post=26446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}