{"id":25378,"date":"2020-01-17T14:50:07","date_gmt":"2020-01-28T13:30:47","guid":{"rendered":"https:\/\/www.groupeplastika.com\/?post_type=product&#038;p=25378"},"modified":"2020-01-28T08:30:47","modified_gmt":"2020-01-28T13:30:47","slug":"bracket-3338","status":"publish","type":"product","link":"https:\/\/www.groupeplastika.com\/en\/produit\/bracket-3338\/","title":{"rendered":"Bracket"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":24923,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1742],"product_tag":[],"class_list":{"0":"post-25378","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-brackets-and-dentil-blocks-brackets","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bracket - Groupe Plastika<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.groupeplastika.com\/en\/produit\/bracket-3338\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bracket - Groupe Plastika\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.groupeplastika.com\/en\/produit\/bracket-3338\/\" \/>\n<meta property=\"og:site_name\" content=\"Groupe Plastika\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.groupeplastika.com\/wp-content\/uploads\/2024\/12\/3338.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1084\" \/>\n\t<meta property=\"og:image:height\" content=\"1156\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/bracket-3338\\\/\",\"url\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/bracket-3338\\\/\",\"name\":\"Bracket - Groupe Plastika\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/bracket-3338\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/bracket-3338\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.groupeplastika.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/3338.png\",\"datePublished\":\"2020-01-28T13:30:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/bracket-3338\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/bracket-3338\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/bracket-3338\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.groupeplastika.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/3338.png\",\"contentUrl\":\"https:\\\/\\\/www.groupeplastika.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/3338.png\",\"width\":1232,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/produit\\\/bracket-3338\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bracket\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/#website\",\"url\":\"https:\\\/\\\/www.groupeplastika.com\\\/\",\"name\":\"Groupe Plastika\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.groupeplastika.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bracket - Groupe Plastika","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.groupeplastika.com\/en\/produit\/bracket-3338\/","og_locale":"en_US","og_type":"article","og_title":"Bracket - Groupe Plastika","og_url":"https:\/\/www.groupeplastika.com\/en\/produit\/bracket-3338\/","og_site_name":"Groupe Plastika","og_image":[{"width":1084,"height":1156,"url":"https:\/\/www.groupeplastika.com\/wp-content\/uploads\/2024\/12\/3338.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.groupeplastika.com\/en\/produit\/bracket-3338\/","url":"https:\/\/www.groupeplastika.com\/en\/produit\/bracket-3338\/","name":"Bracket - Groupe Plastika","isPartOf":{"@id":"https:\/\/www.groupeplastika.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.groupeplastika.com\/en\/produit\/bracket-3338\/#primaryimage"},"image":{"@id":"https:\/\/www.groupeplastika.com\/en\/produit\/bracket-3338\/#primaryimage"},"thumbnailUrl":"https:\/\/www.groupeplastika.com\/wp-content\/uploads\/2024\/12\/3338.png","datePublished":"2020-01-28T13:30:47+00:00","breadcrumb":{"@id":"https:\/\/www.groupeplastika.com\/en\/produit\/bracket-3338\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.groupeplastika.com\/en\/produit\/bracket-3338\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.groupeplastika.com\/en\/produit\/bracket-3338\/#primaryimage","url":"https:\/\/www.groupeplastika.com\/wp-content\/uploads\/2024\/12\/3338.png","contentUrl":"https:\/\/www.groupeplastika.com\/wp-content\/uploads\/2024\/12\/3338.png","width":1232,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.groupeplastika.com\/en\/produit\/bracket-3338\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.groupeplastika.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.groupeplastika.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Bracket"}]},{"@type":"WebSite","@id":"https:\/\/www.groupeplastika.com\/#website","url":"https:\/\/www.groupeplastika.com\/","name":"Groupe Plastika","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.groupeplastika.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/product\/25378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/comments?post=25378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/media\/24923"}],"wp:attachment":[{"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/media?parent=25378"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/product_brand?post=25378"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/product_cat?post=25378"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/product_tag?post=25378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}