{"id":10250,"date":"2016-03-31T17:44:04","date_gmt":"2016-03-31T16:44:06","guid":{"rendered":"https:\/\/www.groupeplastika.com\/produit\/bracket-3321-en\/"},"modified":"2016-07-15T13:58:59","modified_gmt":"2016-07-15T12:58:59","slug":"bracket-3321-en","status":"publish","type":"product","link":"https:\/\/www.groupeplastika.com\/en\/produit\/bracket-3321-en\/","title":{"rendered":"Bracket"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":15489,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1742],"product_tag":[],"class_list":{"0":"post-10250","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-brackets-and-dentil-blocks-brackets","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bracket - Groupe Plastika<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.groupeplastika.com\/produit\/support-3321\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bracket - Groupe Plastika\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.groupeplastika.com\/produit\/support-3321\/\" \/>\n<meta property=\"og:site_name\" content=\"Groupe Plastika\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-15T12:58:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.groupeplastika.com\/wp-content\/uploads\/\/2016\/05\/3321.png\" \/>\n\t<meta property=\"og:image:width\" content=\"903\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/produit\\\/support-3321\\\/\",\"url\":\"https:\\\/\\\/www.groupeplastika.com\\\/produit\\\/support-3321\\\/\",\"name\":\"Bracket - Groupe Plastika\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/produit\\\/support-3321\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/produit\\\/support-3321\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.groupeplastika.com\\\/wp-content\\\/uploads\\\/\\\/2016\\\/05\\\/3321.png\",\"datePublished\":\"2016-03-31T16:44:06+00:00\",\"dateModified\":\"2016-07-15T12:58:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/produit\\\/support-3321\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.groupeplastika.com\\\/produit\\\/support-3321\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/produit\\\/support-3321\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.groupeplastika.com\\\/wp-content\\\/uploads\\\/\\\/2016\\\/05\\\/3321.png\",\"contentUrl\":\"https:\\\/\\\/www.groupeplastika.com\\\/wp-content\\\/uploads\\\/\\\/2016\\\/05\\\/3321.png\",\"width\":903,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/produit\\\/support-3321\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.groupeplastika.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bracket\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.groupeplastika.com\\\/#website\",\"url\":\"https:\\\/\\\/www.groupeplastika.com\\\/\",\"name\":\"Groupe Plastika\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.groupeplastika.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bracket - Groupe Plastika","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.groupeplastika.com\/produit\/support-3321\/","og_locale":"en_US","og_type":"article","og_title":"Bracket - Groupe Plastika","og_url":"https:\/\/www.groupeplastika.com\/produit\/support-3321\/","og_site_name":"Groupe Plastika","article_modified_time":"2016-07-15T12:58:59+00:00","og_image":[{"width":903,"height":1500,"url":"https:\/\/www.groupeplastika.com\/wp-content\/uploads\/\/2016\/05\/3321.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.groupeplastika.com\/produit\/support-3321\/","url":"https:\/\/www.groupeplastika.com\/produit\/support-3321\/","name":"Bracket - Groupe Plastika","isPartOf":{"@id":"https:\/\/www.groupeplastika.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.groupeplastika.com\/produit\/support-3321\/#primaryimage"},"image":{"@id":"https:\/\/www.groupeplastika.com\/produit\/support-3321\/#primaryimage"},"thumbnailUrl":"https:\/\/www.groupeplastika.com\/wp-content\/uploads\/\/2016\/05\/3321.png","datePublished":"2016-03-31T16:44:06+00:00","dateModified":"2016-07-15T12:58:59+00:00","breadcrumb":{"@id":"https:\/\/www.groupeplastika.com\/produit\/support-3321\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.groupeplastika.com\/produit\/support-3321\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.groupeplastika.com\/produit\/support-3321\/#primaryimage","url":"https:\/\/www.groupeplastika.com\/wp-content\/uploads\/\/2016\/05\/3321.png","contentUrl":"https:\/\/www.groupeplastika.com\/wp-content\/uploads\/\/2016\/05\/3321.png","width":903,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.groupeplastika.com\/produit\/support-3321\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.groupeplastika.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.groupeplastika.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Bracket"}]},{"@type":"WebSite","@id":"https:\/\/www.groupeplastika.com\/#website","url":"https:\/\/www.groupeplastika.com\/","name":"Groupe Plastika","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.groupeplastika.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/product\/10250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/comments?post=10250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/media\/15489"}],"wp:attachment":[{"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/media?parent=10250"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/product_brand?post=10250"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/product_cat?post=10250"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.groupeplastika.com\/en\/wp-json\/wp\/v2\/product_tag?post=10250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}